{"id":824,"date":"2019-03-13T14:08:09","date_gmt":"2019-03-13T13:08:09","guid":{"rendered":"https:\/\/www.kosmetikfuchs.de\/magazin\/?p=824"},"modified":"2024-04-03T13:11:40","modified_gmt":"2024-04-03T11:11:40","slug":"mikroplastik-in-kosmetik","status":"publish","type":"post","link":"https:\/\/www.kosmetikfuchs.de\/magazin\/mikroplastik-in-kosmetik\/","title":{"rendered":"Mikroplastik in Kosmetik"},"content":{"rendered":"<h2>\u00ab Plastikfreie Alternativen entdecken \u00bb<\/h2>\n<p style=\"text-align: justify;\"><strong>Wirft man einen Blick in die Statistiken f\u00fcr den Plastikverbrauch oder sieht sich die Massen an Plastik an, die wir t\u00e4glich in der Hand haben, wird das Ausma\u00df des Problems schnell bewusst. Wir produzieren viel zu viel Plastikm\u00fcll und das hat verheerende Folgen f\u00fcr unsere Umwelt. Mikroplastik in Kosmetik ist ebenso ein Teil dieses Desasters f\u00fcr die Umwelt, denn diese landet am Ende unter anderem in den Gew\u00e4ssern. \u00dcbrigens: Egal ob Peeling, Duschgel oder Shampoo \u2013 ohne Mikroplastik stellt eher die Ausnahme dar. Doch findet hier gl\u00fccklicherweise bereits ein Umdenken statt: Es wird vermehrt \u00fcber die Folgen aufgekl\u00e4rt, an das Umweltbewusstsein der Verbraucher appelliert und auch einige Kosmetikhersteller ziehen mit und bieten immer mehr mikroplastikfreie Alternativen in ihrem Sortiment an. <\/strong><\/p>\n<h2>Was ist Mikroplastik?<\/h2>\n<p style=\"text-align: justify;\">Hiermit werden Partikel aus Plastik bezeichnet, die kleiner als f\u00fcnf Millimeter sind. Die Teilchen sind so winzig, dass sie f\u00fcr das menschliche Auge kaum erkennbar sind. Eine genaue Definition ist schwierig \u2013 allein \u00fcber die Gr\u00f6\u00dfe der Teilchen herrscht Einigkeit. Kunststoffe, die fl\u00fcssig, wachs- oder gelf\u00f6rmig sind, geh\u00f6ren (noch) nicht in den Mikroplastikbereich. Hergestellt wird Mikroplastik zum einen industriell, mit dem Ziel es in unserer Haut- und Haarpflege einzusetzen. Aber nicht nur hier, auch als \u00dcberbleibsel von gro\u00dfen Kunststoffartikeln entsteht es. Zum Beispiel wenn T\u00fcten aus Plastik mit der Zeit in ihre Einzelteile zerfallen. Unter anderem aus diesem Grund sind Plastikt\u00fcten, die vorher beim Einkaufen Standard waren, so in Verruf geraten.<\/p>\n<h2>Vielfach in unserem Bad: Produkte mit Mikroplastik<\/h2>\n<figure id=\"attachment_827\" aria-describedby=\"caption-attachment-827\" style=\"width: 850px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-827 size-full\" title=\"In vielen herk\u00f6mmlichen Pflegeprodukten ist Mikroplastik\" src=\"https:\/\/www.kosmetikfuchs.de\/magazin\/wp-content\/uploads\/2019\/03\/Badezimmerprodukte.jpg\" alt=\"In vielen herk\u00f6mmlichen Pflegeprodukten ist Mikroplastik\" width=\"850\" height=\"439\" srcset=\"https:\/\/www.kosmetikfuchs.de\/magazin\/wp-content\/uploads\/2019\/03\/Badezimmerprodukte.jpg 850w, https:\/\/www.kosmetikfuchs.de\/magazin\/wp-content\/uploads\/2019\/03\/Badezimmerprodukte-300x155.jpg 300w, https:\/\/www.kosmetikfuchs.de\/magazin\/wp-content\/uploads\/2019\/03\/Badezimmerprodukte-768x397.jpg 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/><figcaption id=\"caption-attachment-827\" class=\"wp-caption-text\">\u00a9 BillionPhotos.com \u2013 stock.adobe.com<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Ein bekanntes Beispiel f\u00fcr den Einsatz der Mini-Plastikk\u00fcgelchen sind Peelings oder Pflegeprodukte mit Peelingeffekt. Um abgestorbene Hautsch\u00fcppchen oder Schmutz zu entfernen, ist ein Peeling mit k\u00f6rnigem Material versehen. Dieses funktioniert wie eine Art Schn\u00f6rkelpapier und besteht in vielen F\u00e4llen aus kleinen Kunststoffk\u00fcgelchen (Microbeads). Ziel eines Peelings ist es, die Haut zu reinigen und die Poren zu \u00f6ffnen, damit die nachfolgende Hautpflege besser aufgenommen werden kann. Auch in Duschgels, Cremes beziehungsweise Rasiercremes kommen sie zum Einsatz. In Cremes wird Mikroplastik als Bindemittel verwendet, um die Konsistenz zu verbessern und damit der typische Film entsteht. Dasselbe gilt f\u00fcr dekorative Kosmetik, wie Lippenstift. Polymere kommen zum Beispiel in Produkten zur Haarfixierung zum Einsatz, dazu geh\u00f6ren Haarsprays, Haargels oder Haarwachs. Auch wenn fl\u00fcssige beziehungsweise gelartige Polymeere nicht zu Mikroplastiken geh\u00f6ren, sind sie ebenso problematisch f\u00fcr unsere Umwelt und sollten deshalb vermieden werden. Weitere Beispiele f\u00fcr m\u00f6gliche Kosmetikprodukte mit Mikroplastik sind:<\/p>\n<ul>\n<li>Haarshampoo und Sp\u00fclungen<\/li>\n<li>Sonnencremes<\/li>\n<li>Make-up<\/li>\n<li>Zahnpasta<\/li>\n<li>Gesichtsmasken<\/li>\n<li>Bodylotion<\/li>\n<li>Seife<\/li>\n<li>Mascara<\/li>\n<li>Handcreme<\/li>\n<\/ul>\n<blockquote>\n<p style=\"text-align: justify;\">Letztendlich k\u00f6nnen die Mikropartikel aus Plastik in jeder Art von K\u00f6rper- und Gesichtspflege vorkommen und f\u00fcr Verbraucher ist es gar nicht so einfach, Mikroplastik in Kosmetik zu erkennen.<\/p>\n<\/blockquote>\n<h2>Warum Mikroplastik sch\u00e4dlich f\u00fcr die Umwelt ist<\/h2>\n<p style=\"text-align: justify;\">Die kleinen Partikel aus Plastik, die sich beispielsweise in einem Peeling befinden, werden nach dem Auftragen auf der Haut abgewaschen und gelangen so in die Umwelt. Kl\u00e4ranlagen k\u00f6nnen die winzigen Teilchen nicht vollst\u00e4ndig filtern und so haben diese leichtes Spiel, ins Abwasser und damit in unsere Gew\u00e4sser zu gelangen. Durch den Kl\u00e4rschlamm sind nicht nur die Meere, sondern auch Felder und Luft betroffen. Plastikm\u00fcll stellt eine enorme Umweltbelastung dar. Das liegt vor allem daran, dass Plastik nicht biologisch abbaubar ist. Es bleibt einige Hundert Jahre an den Ablagerungsorten (zum Beispiel den Weltmeeren) liegen und richtet dort verehrende Sch\u00e4den an. Neben dem wird es aus dem immer knapper werdenden Rohstoff Erd\u00f6l hergestellt. Meeresorganismen verwechseln das Plastik mit Nahrung, je kleiner es ist, desto h\u00f6her ist dabei die Gefahr. Bei den Meeresbewohnern f\u00fchrt dies zu physiologischen Ver\u00e4nderungen, das kann bis zu Tumorbildungen und vorzeitigem Verenden gehen. Die kleinen Mikroplastikteilchen funktionieren im Meer, wie ein Giftstoffmagnet. Es haften dort zahlreiche Schadstoffe an, welche von den Lebewesen aufgenommen werden. Auch f\u00fcr uns Menschen bleibt das nicht ohne problematische Konsequenzen, denn wir essen die Meereslebewesen. In Trinkwasser und anderen Getr\u00e4nken landen die mikroskopisch kleinen Partikel aus Plastik auch.<\/p>\n<figure id=\"attachment_830\" aria-describedby=\"caption-attachment-830\" style=\"width: 850px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-830 size-full\" title=\"Sch\u00e4dlich f\u00fcr Umwelt und die Haut\" src=\"https:\/\/www.kosmetikfuchs.de\/magazin\/wp-content\/uploads\/2019\/03\/Mikroplastik-in-Kosmetik.jpg\" alt=\"Sch\u00e4dlich f\u00fcr Umwelt und die Haut\" width=\"850\" height=\"425\" srcset=\"https:\/\/www.kosmetikfuchs.de\/magazin\/wp-content\/uploads\/2019\/03\/Mikroplastik-in-Kosmetik.jpg 850w, https:\/\/www.kosmetikfuchs.de\/magazin\/wp-content\/uploads\/2019\/03\/Mikroplastik-in-Kosmetik-300x150.jpg 300w, https:\/\/www.kosmetikfuchs.de\/magazin\/wp-content\/uploads\/2019\/03\/Mikroplastik-in-Kosmetik-768x384.jpg 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/><figcaption id=\"caption-attachment-830\" class=\"wp-caption-text\">\u00a9 lilo \u2013 stock.adobe.com<\/figcaption><\/figure>\n<h2>Wie finden Sie eine Pflege ohne Mikroplastik?<\/h2>\n<p style=\"text-align: justify;\">F\u00fcr Verbraucher ist es gar nicht so leicht zu erkennen, welche Pflegeprodukte mikroplastikfrei sind. Erste Anhaltspunkte bieten verschiedene Listen und Datenbanken im Internet, die Mikroplastik in Kosmetik ausfindig machen. Leider ist dies teilweise sehr aufwendig und die Erkl\u00e4rungen nicht immer leicht zu verstehen. Hier m\u00fcsste es eindeutig mehr Transparenz geben und vor allem verst\u00e4ndliche Informationen, die den Verbraucher dar\u00fcber aufkl\u00e4ren, was genau in seinen Produkten enthalten ist. Auch spezielle Apps k\u00f6nnen Sie beim Einkaufen unterst\u00fctzen, diese zeigen ihnen auf, ob ein Produkt Mikropartikel aus Plastik enth\u00e4lt. Werfen Sie einen Blick auf die Inhaltsstoffe und finden Sie dort unter anderem folgende Abk\u00fcrzungen ist das Produkt nicht mikroplastikfrei:<\/p>\n<ul>\n<li>PP (Polypropylen)<\/li>\n<li>PET (Polyethylenterephthalat)<\/li>\n<li>PA (Polyacrylat)<\/li>\n<li>PE (Polyethylen)<\/li>\n<li>EVA (Ethylen-Vinylacetat-Copolymereist)<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Dasselbe gilt f\u00fcr Nylon-6 und 12 oder AC (Acrylates Copolymer). Ein zuverl\u00e4ssiges Siegel f\u00fcr Kosmetik ohne Plastik ist zertifizierte Naturkosmetik. Diese l\u00e4sst keine Mikroplastikzus\u00e4tze zu und verwendet Alternativstoffe beziehungsweise pflanzliche Inhaltsstoffe, die keine Belastung f\u00fcr die Umwelt darstellen. Das sind zum Beispiel Tonerde, Kieselerde, Traubenkerne oder Weizenkleie \u2013 diese f\u00fchren ebenso zu einem Peelingeffekt, wie die Variante aus Plastik. Wahre Bio-Kosmetik beziehungsweise Naturkosmetik erkennen Sie an den auf der Verpackung sichtbaren G\u00fctesiegeln:<\/p>\n<ul>\n<li>BDIH,<\/li>\n<li>Ecocert Biokosmetik oder<\/li>\n<li>NaTrue &#8211; organic cosmetics.<\/li>\n<\/ul>\n<h2>Kosmetik ohne Mikroplastik \u2013 diese Marken verzichten<\/h2>\n<p>Verifizierte Bio-Kosmetik, welche mit den oben genannten Siegeln versehen ist, kann bedenkenlos gekauft und verwendet werden. Im Folgenden sind verschiedene Marken dargestellt, die mikroplastikfreie Produkte anbieten.<\/p>\n<figure id=\"attachment_832\" aria-describedby=\"caption-attachment-832\" style=\"width: 850px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-832 size-full\" title=\"Kosmetik ohne Mikroplastik\" src=\"https:\/\/www.kosmetikfuchs.de\/magazin\/wp-content\/uploads\/2019\/03\/Creme.jpg\" alt=\"Kosmetik ohne Mikroplastik\" width=\"850\" height=\"479\" srcset=\"https:\/\/www.kosmetikfuchs.de\/magazin\/wp-content\/uploads\/2019\/03\/Creme.jpg 850w, https:\/\/www.kosmetikfuchs.de\/magazin\/wp-content\/uploads\/2019\/03\/Creme-300x169.jpg 300w, https:\/\/www.kosmetikfuchs.de\/magazin\/wp-content\/uploads\/2019\/03\/Creme-768x433.jpg 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/><figcaption id=\"caption-attachment-832\" class=\"wp-caption-text\">\u00a9 Antonioguillem \u2013 stock.adobe.com<\/figcaption><\/figure>\n<h3>Annemarie B\u00f6rlind<\/h3>\n<p style=\"text-align: justify;\">Die <a href=\"https:\/\/www.kosmetikfuchs.de\/brands\/annemarie-boerlind\/products\">Bio-Kosmetik von Annemarie B\u00f6rlind<\/a> kommt ohne Mikroplastik aus. Die Marke gilt als zertifizierter Hersteller von Naturkosmetik und setzt auf umwelt- und gesundheitsfreundliche Pflegeprodukte. In dem <a href=\"https:\/\/www.kosmetikfuchs.de\/brands\/annemarie-boerlind\/peelings\">Effekt Peeling von Annemarie B\u00f6rlind<\/a> sind zum Beispiel statt Mikroplastikteilchen K\u00fcgelchen aus Jojobawachs verarbeitet. Diese l\u00f6sen Verschmutzungen und Hautreste auf nat\u00fcrliche Weise und bereiten die Haut optimal auf die folgende Gesichtspflege vor. F\u00fcr eine besonders cremige Textur, welche die Haut weich und geschmeidig macht, sorgt die biozertifizierte Sheabutter.<\/p>\n<p><a href=\"https:\/\/www.kosmetikfuchs.de\/10513\/annemarie-boerlind\/effekt-peeling-50ml\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-835 size-full\" title=\"Enzym-Peeling, 30g | Annemarie B\u00f6rlind\" src=\"https:\/\/www.kosmetikfuchs.de\/magazin\/wp-content\/uploads\/2019\/03\/ENZYM-PEELING-30g.jpg\" alt=\"ENZYM-PEELING, 30g\" width=\"400\" height=\"352\" srcset=\"https:\/\/www.kosmetikfuchs.de\/magazin\/wp-content\/uploads\/2019\/03\/ENZYM-PEELING-30g.jpg 400w, https:\/\/www.kosmetikfuchs.de\/magazin\/wp-content\/uploads\/2019\/03\/ENZYM-PEELING-30g-300x264.jpg 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/a>\u00a0<a href=\"https:\/\/www.kosmetikfuchs.de\/10513\/annemarie-boerlind\/effekt-peeling-50ml\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-837 size-full\" title=\"Effekt-Peeling, 50ml | Annemarie B\u00f6rlind\" src=\"https:\/\/www.kosmetikfuchs.de\/magazin\/wp-content\/uploads\/2019\/03\/EFFEKT-PEELING-50ml_.jpg\" alt=\"EFFEKT-PEELING, 50ml\" width=\"401\" height=\"352\" srcset=\"https:\/\/www.kosmetikfuchs.de\/magazin\/wp-content\/uploads\/2019\/03\/EFFEKT-PEELING-50ml_.jpg 401w, https:\/\/www.kosmetikfuchs.de\/magazin\/wp-content\/uploads\/2019\/03\/EFFEKT-PEELING-50ml_-300x263.jpg 300w\" sizes=\"(max-width: 401px) 100vw, 401px\" \/><\/a><\/p>\n<h3>Dr. Hauschka<\/h3>\n<p style=\"text-align: justify;\">Die <a href=\"https:\/\/www.kosmetikfuchs.de\/brands\/dr-hauschka\/products\">Naturkosmetik von Dr. Hauschka<\/a> ist ebenfalls mikroplastikfrei und kann bedenkenlos verwendet werden. Das komplette Sortiment der Hautpflege ist mit dem BDIH-Siegel versehen, welches auf kontrollierte Naturkosmetik hindeutet. Zudem steht sie noch unter dem internationalen Qualit\u00e4tssiegel f\u00fcr Natur- und Biokosmetik &#8222;NATRUE&#8220;. Neben Mikropartikeln aus Plastik wird auch auf synthetische Duftstoffe sowie Farb-, und Konservierungsstoffe verzichtet. Stattdessen enthalten sind Ausz\u00fcge aus wertvollen Heilpflanzen, die Ihre Haut nat\u00fcrlich pflegen und die innere Balance wiederherstellen. Dr. Hauschka betont dabei die Wichtigkeit jedes einzelnen Inhaltsstoffes, aber besonders das wirkungsvolle Zusammenspiel der verschiedenen Ingredienzien. Das Sortiment ist dabei sehr vielseitig, es umfasst:<\/p>\n<ul>\n<li>Gesichtspflege<\/li>\n<li>Regenerationspflege<\/li>\n<li>Hauschka Med f\u00fcr besonders Hautbed\u00fcrfnisse<\/li>\n<li>Haarpflege<\/li>\n<li>K\u00f6rperpflege<\/li>\n<li>dekorative Kosmetik<\/li>\n<li>B\u00e4der Wohlf\u00fchlsets<\/li>\n<\/ul>\n<h3><a href=\"https:\/\/www.kosmetikfuchs.de\/1646\/dr.-hauschka\/regeneration-tagescreme-40-ml\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-839 size-full\" title=\"Regeneration Tagescreme, 40 ml\" src=\"https:\/\/www.kosmetikfuchs.de\/magazin\/wp-content\/uploads\/2019\/03\/Regeneration-Tagescreme-40-ml.jpg\" alt=\"Regeneration Tagescreme, 40 ml\" width=\"250\" height=\"285\" \/><\/a>\u00a0<a href=\"https:\/\/www.kosmetikfuchs.de\/1654\/dr.-hauschka\/gesichtsmilch-30ml\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-840 size-full\" title=\"Gesichtsmilch, 30 ml\" src=\"https:\/\/www.kosmetikfuchs.de\/magazin\/wp-content\/uploads\/2019\/03\/Gesichtsmilch-30-ml.jpg\" alt=\"Gesichtsmilch, 30 ml\" width=\"268\" height=\"285\" \/><\/a>\u00a0<a href=\"https:\/\/www.kosmetikfuchs.de\/5170\/dr.-hauschka\/mandel-koerperbalsam-145ml\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-842 size-full\" title=\"Mandel K\u00f6rperbalsam, 145ml\" src=\"https:\/\/www.kosmetikfuchs.de\/magazin\/wp-content\/uploads\/2019\/03\/Mandel-K\u00f6rperbalsam-145ml.jpg\" alt=\"Mandel K\u00f6rperbalsam, 145ml\" width=\"250\" height=\"285\" \/><\/a><\/h3>\n<h3>Charlotte Meentzen<\/h3>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.kosmetikfuchs.de\/brands\/charlotte-meentzen\/products\">Charlotte Meentzen Kosmetik<\/a> tr\u00e4gt ebenfalls das internationale Qualit\u00e4tssiegel f\u00fcr Natur- und Biokosmetik &#8222;NATRUE&#8220;. Zudem verf\u00fcgt sie noch \u00fcber die ISO-UMWELTMANAGEMENT ZERTIFIZIERUNG und das GMP-Zertifikat (Good Manufacturing Practice). Das Unternehmen vertraut allein auf nat\u00fcrliche Wirkstoffe und hat sich h\u00f6chste Qualit\u00e4t bei nachhaltiger Herstellung auf die Fahne geschrieben. Ihre Inhaltsstoffe gewinnt es aus der Kraft der Natur. Dabei sind die einzelnen Produkte passgenau auf die verschiedenen Bed\u00fcrfnisse der Haut abgestimmt. Das Charlotte Meentzen Sortiment umfasst:<\/p>\n<ul>\n<li>eine Regenerationspflege Palette,<\/li>\n<li>eine hochwertige Q10 Anti-Aging Pflege oder<\/li>\n<li>eine exotische Everyday-Beautylinie.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab Plastikfreie Alternativen entdecken \u00bb Wirft man einen Blick in die Statistiken f\u00fcr den Plastikverbrauch oder sieht sich die Massen an Plastik an, die wir t\u00e4glich in der Hand haben, wird das Ausma\u00df des Problems schnell bewusst. Wir produzieren viel zu viel Plastikm\u00fcll und das hat verheerende Folgen f\u00fcr unsere Umwelt. Mikroplastik in Kosmetik ist &hellip;<\/p>\n","protected":false},"author":1,"featured_media":844,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[594],"tags":[83,111,23,25,153,151,152,24,82,154],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mikroplastik in Kosmetik - Kosmetikfuchs Magazin<\/title>\n<meta name=\"description\" content=\"Das Kosmetikfuchs Magazin \u00fcber Mikroplastik in Kosmetik &amp; zeigt plastikfreie Alternativen von \u2714Annemarie B\u00f6rlind \u2714Dr. Hauschka \u2714Charlotte Meentzen\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kosmetikfuchs.de\/magazin\/mikroplastik-in-kosmetik\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mikroplastik in Kosmetik - Kosmetikfuchs Magazin\" \/>\n<meta property=\"og:description\" content=\"Das Kosmetikfuchs Magazin \u00fcber Mikroplastik in Kosmetik &amp; zeigt plastikfreie Alternativen von \u2714Annemarie B\u00f6rlind \u2714Dr. Hauschka \u2714Charlotte Meentzen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kosmetikfuchs.de\/magazin\/mikroplastik-in-kosmetik\/\" \/>\n<meta property=\"og:site_name\" content=\"Kosmetikfuchs Magazin\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-13T13:08:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-03T11:11:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kosmetikfuchs.de\/magazin\/wp-content\/uploads\/2019\/03\/Cremen.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"478\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.kosmetikfuchs.de\/magazin\/mikroplastik-in-kosmetik\/\",\"url\":\"https:\/\/www.kosmetikfuchs.de\/magazin\/mikroplastik-in-kosmetik\/\",\"name\":\"Mikroplastik in Kosmetik - Kosmetikfuchs Magazin\",\"isPartOf\":{\"@id\":\"https:\/\/www.kosmetikfuchs.de\/magazin\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.kosmetikfuchs.de\/magazin\/mikroplastik-in-kosmetik\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.kosmetikfuchs.de\/magazin\/mikroplastik-in-kosmetik\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.kosmetikfuchs.de\/magazin\/wp-content\/uploads\/2019\/03\/Cremen.jpg\",\"datePublished\":\"2019-03-13T13:08:09+00:00\",\"dateModified\":\"2024-04-03T11:11:40+00:00\",\"author\":{\"@id\":\"https:\/\/www.kosmetikfuchs.de\/magazin\/#\/schema\/person\/d74441dfe7021cf7301a89aa8423d147\"},\"description\":\"Das Kosmetikfuchs Magazin \u00fcber Mikroplastik in Kosmetik & zeigt plastikfreie Alternativen von \u2714Annemarie B\u00f6rlind \u2714Dr. Hauschka \u2714Charlotte Meentzen\",\"breadcrumb\":{\"@id\":\"https:\/\/www.kosmetikfuchs.de\/magazin\/mikroplastik-in-kosmetik\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.kosmetikfuchs.de\/magazin\/mikroplastik-in-kosmetik\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.kosmetikfuchs.de\/magazin\/mikroplastik-in-kosmetik\/#primaryimage\",\"url\":\"https:\/\/www.kosmetikfuchs.de\/magazin\/wp-content\/uploads\/2019\/03\/Cremen.jpg\",\"contentUrl\":\"https:\/\/www.kosmetikfuchs.de\/magazin\/wp-content\/uploads\/2019\/03\/Cremen.jpg\",\"width\":850,\"height\":478,\"caption\":\"\u00a9 Andrey Cherkasov \u2013 stock.adobe.com\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.kosmetikfuchs.de\/magazin\/mikroplastik-in-kosmetik\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.kosmetikfuchs.de\/magazin\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mikroplastik in Kosmetik\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.kosmetikfuchs.de\/magazin\/#website\",\"url\":\"https:\/\/www.kosmetikfuchs.de\/magazin\/\",\"name\":\"Kosmetikfuchs Magazin\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.kosmetikfuchs.de\/magazin\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.kosmetikfuchs.de\/magazin\/#\/schema\/person\/d74441dfe7021cf7301a89aa8423d147\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.kosmetikfuchs.de\/magazin\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a794a4fe8a9b9c52241597eb381dfa2e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a794a4fe8a9b9c52241597eb381dfa2e?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/www.kosmetikfuchs.de\/magazin\/author\/321456\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mikroplastik in Kosmetik - Kosmetikfuchs Magazin","description":"Das Kosmetikfuchs Magazin \u00fcber Mikroplastik in Kosmetik & zeigt plastikfreie Alternativen von \u2714Annemarie B\u00f6rlind \u2714Dr. Hauschka \u2714Charlotte Meentzen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kosmetikfuchs.de\/magazin\/mikroplastik-in-kosmetik\/","og_locale":"de_DE","og_type":"article","og_title":"Mikroplastik in Kosmetik - Kosmetikfuchs Magazin","og_description":"Das Kosmetikfuchs Magazin \u00fcber Mikroplastik in Kosmetik & zeigt plastikfreie Alternativen von \u2714Annemarie B\u00f6rlind \u2714Dr. Hauschka \u2714Charlotte Meentzen","og_url":"https:\/\/www.kosmetikfuchs.de\/magazin\/mikroplastik-in-kosmetik\/","og_site_name":"Kosmetikfuchs Magazin","article_published_time":"2019-03-13T13:08:09+00:00","article_modified_time":"2024-04-03T11:11:40+00:00","og_image":[{"width":850,"height":478,"url":"https:\/\/www.kosmetikfuchs.de\/magazin\/wp-content\/uploads\/2019\/03\/Cremen.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"admin","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.kosmetikfuchs.de\/magazin\/mikroplastik-in-kosmetik\/","url":"https:\/\/www.kosmetikfuchs.de\/magazin\/mikroplastik-in-kosmetik\/","name":"Mikroplastik in Kosmetik - Kosmetikfuchs Magazin","isPartOf":{"@id":"https:\/\/www.kosmetikfuchs.de\/magazin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kosmetikfuchs.de\/magazin\/mikroplastik-in-kosmetik\/#primaryimage"},"image":{"@id":"https:\/\/www.kosmetikfuchs.de\/magazin\/mikroplastik-in-kosmetik\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kosmetikfuchs.de\/magazin\/wp-content\/uploads\/2019\/03\/Cremen.jpg","datePublished":"2019-03-13T13:08:09+00:00","dateModified":"2024-04-03T11:11:40+00:00","author":{"@id":"https:\/\/www.kosmetikfuchs.de\/magazin\/#\/schema\/person\/d74441dfe7021cf7301a89aa8423d147"},"description":"Das Kosmetikfuchs Magazin \u00fcber Mikroplastik in Kosmetik & zeigt plastikfreie Alternativen von \u2714Annemarie B\u00f6rlind \u2714Dr. Hauschka \u2714Charlotte Meentzen","breadcrumb":{"@id":"https:\/\/www.kosmetikfuchs.de\/magazin\/mikroplastik-in-kosmetik\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kosmetikfuchs.de\/magazin\/mikroplastik-in-kosmetik\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kosmetikfuchs.de\/magazin\/mikroplastik-in-kosmetik\/#primaryimage","url":"https:\/\/www.kosmetikfuchs.de\/magazin\/wp-content\/uploads\/2019\/03\/Cremen.jpg","contentUrl":"https:\/\/www.kosmetikfuchs.de\/magazin\/wp-content\/uploads\/2019\/03\/Cremen.jpg","width":850,"height":478,"caption":"\u00a9 Andrey Cherkasov \u2013 stock.adobe.com"},{"@type":"BreadcrumbList","@id":"https:\/\/www.kosmetikfuchs.de\/magazin\/mikroplastik-in-kosmetik\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.kosmetikfuchs.de\/magazin\/"},{"@type":"ListItem","position":2,"name":"Mikroplastik in Kosmetik"}]},{"@type":"WebSite","@id":"https:\/\/www.kosmetikfuchs.de\/magazin\/#website","url":"https:\/\/www.kosmetikfuchs.de\/magazin\/","name":"Kosmetikfuchs Magazin","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kosmetikfuchs.de\/magazin\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.kosmetikfuchs.de\/magazin\/#\/schema\/person\/d74441dfe7021cf7301a89aa8423d147","name":"admin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kosmetikfuchs.de\/magazin\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a794a4fe8a9b9c52241597eb381dfa2e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a794a4fe8a9b9c52241597eb381dfa2e?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/www.kosmetikfuchs.de\/magazin\/author\/321456\/"}]}},"_links":{"self":[{"href":"https:\/\/www.kosmetikfuchs.de\/magazin\/wp-json\/wp\/v2\/posts\/824"}],"collection":[{"href":"https:\/\/www.kosmetikfuchs.de\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kosmetikfuchs.de\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kosmetikfuchs.de\/magazin\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kosmetikfuchs.de\/magazin\/wp-json\/wp\/v2\/comments?post=824"}],"version-history":[{"count":14,"href":"https:\/\/www.kosmetikfuchs.de\/magazin\/wp-json\/wp\/v2\/posts\/824\/revisions"}],"predecessor-version":[{"id":8400,"href":"https:\/\/www.kosmetikfuchs.de\/magazin\/wp-json\/wp\/v2\/posts\/824\/revisions\/8400"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kosmetikfuchs.de\/magazin\/wp-json\/wp\/v2\/media\/844"}],"wp:attachment":[{"href":"https:\/\/www.kosmetikfuchs.de\/magazin\/wp-json\/wp\/v2\/media?parent=824"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kosmetikfuchs.de\/magazin\/wp-json\/wp\/v2\/categories?post=824"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kosmetikfuchs.de\/magazin\/wp-json\/wp\/v2\/tags?post=824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}